{"id":50,"count":122,"description":"","link":"https:\/\/teacherstickers.com\/au\/product-category\/other-themes\/","name":"Other themes","slug":"other-themes","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":11,"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Other themes Archives | Teacher Stickers<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/teacherstickers.com\/au\/product-category\/other-themes\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Other themes Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/teacherstickers.com\/au\/product-category\/other-themes\/\" \/>\n<meta property=\"og:site_name\" content=\"Teacher Stickers\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@teachersticker\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/teacherstickers.com\\\/au\\\/product-category\\\/other-themes\\\/\",\"url\":\"https:\\\/\\\/teacherstickers.com\\\/au\\\/product-category\\\/other-themes\\\/\",\"name\":\"Other themes Archives | Teacher Stickers\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/teacherstickers.com\\\/au\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/teacherstickers.com\\\/au\\\/product-category\\\/other-themes\\\/#breadcrumb\"},\"inLanguage\":\"en-AU\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/teacherstickers.com\\\/au\\\/product-category\\\/other-themes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/teacherstickers.com\\\/au\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Other themes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/teacherstickers.com\\\/au\\\/#website\",\"url\":\"https:\\\/\\\/teacherstickers.com\\\/au\\\/\",\"name\":\"Teacher Stickers\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/teacherstickers.com\\\/au\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/teacherstickers.com\\\/au\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-AU\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/teacherstickers.com\\\/au\\\/#organization\",\"name\":\"Teacher Stickers\",\"url\":\"https:\\\/\\\/teacherstickers.com\\\/au\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-AU\",\"@id\":\"https:\\\/\\\/teacherstickers.com\\\/au\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/teacherstickers.com\\\/au\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/teacherstickerssmall.png?fit=205%2C111&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/teacherstickers.com\\\/au\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/teacherstickerssmall.png?fit=205%2C111&ssl=1\",\"width\":205,\"height\":111,\"caption\":\"Teacher Stickers\"},\"image\":{\"@id\":\"https:\\\/\\\/teacherstickers.com\\\/au\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/teacherstickers\",\"https:\\\/\\\/x.com\\\/teachersticker\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Other themes Archives | Teacher Stickers","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/teacherstickers.com\/au\/product-category\/other-themes\/","og_locale":"en_US","og_type":"article","og_title":"Other themes Archives","og_url":"https:\/\/teacherstickers.com\/au\/product-category\/other-themes\/","og_site_name":"Teacher Stickers","twitter_card":"summary_large_image","twitter_site":"@teachersticker","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/teacherstickers.com\/au\/product-category\/other-themes\/","url":"https:\/\/teacherstickers.com\/au\/product-category\/other-themes\/","name":"Other themes Archives | Teacher Stickers","isPartOf":{"@id":"https:\/\/teacherstickers.com\/au\/#website"},"breadcrumb":{"@id":"https:\/\/teacherstickers.com\/au\/product-category\/other-themes\/#breadcrumb"},"inLanguage":"en-AU"},{"@type":"BreadcrumbList","@id":"https:\/\/teacherstickers.com\/au\/product-category\/other-themes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/teacherstickers.com\/au\/"},{"@type":"ListItem","position":2,"name":"Other themes"}]},{"@type":"WebSite","@id":"https:\/\/teacherstickers.com\/au\/#website","url":"https:\/\/teacherstickers.com\/au\/","name":"Teacher Stickers","description":"","publisher":{"@id":"https:\/\/teacherstickers.com\/au\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/teacherstickers.com\/au\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-AU"},{"@type":"Organization","@id":"https:\/\/teacherstickers.com\/au\/#organization","name":"Teacher Stickers","url":"https:\/\/teacherstickers.com\/au\/","logo":{"@type":"ImageObject","inLanguage":"en-AU","@id":"https:\/\/teacherstickers.com\/au\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/teacherstickers.com\/au\/wp-content\/uploads\/2021\/01\/teacherstickerssmall.png?fit=205%2C111&ssl=1","contentUrl":"https:\/\/i0.wp.com\/teacherstickers.com\/au\/wp-content\/uploads\/2021\/01\/teacherstickerssmall.png?fit=205%2C111&ssl=1","width":205,"height":111,"caption":"Teacher Stickers"},"image":{"@id":"https:\/\/teacherstickers.com\/au\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/teacherstickers","https:\/\/x.com\/teachersticker"]}]}},"_links":{"self":[{"href":"https:\/\/teacherstickers.com\/au\/wp-json\/wp\/v2\/product_cat\/50","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teacherstickers.com\/au\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/teacherstickers.com\/au\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/teacherstickers.com\/au\/wp-json\/wp\/v2\/product?product_cat=50"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}